{"id":2812,"date":"2023-03-02T08:52:21","date_gmt":"2023-03-02T08:52:21","guid":{"rendered":"https:\/\/www.polimill.polimi.it\/?page_id=2812"},"modified":"2026-09-01T10:57:19","modified_gmt":"2026-09-01T10:57:19","slug":"parlando-di-noi","status":"publish","type":"page","link":"https:\/\/www.polimill.polimi.it\/en\/parlando-di-noi\/","title":{"rendered":"Talking about us..."},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"2812\" class=\"elementor elementor-2812\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a6f99ec elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"a6f99ec\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;shape_divider_bottom&quot;:&quot;triangle&quot;,&quot;shape_divider_bottom_negative&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-shape elementor-shape-bottom\" aria-hidden=\"true\" data-negative=\"true\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 1000 100\" preserveaspectratio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M500.2,94.7L0,0v100h1000V0L500.2,94.7z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-590d0266\" data-id=\"590d0266\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c4f655c elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"c4f655c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-xl\">Talking about us...<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2a609b3d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2a609b3d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-13a090c8\" data-id=\"13a090c8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7297b0e9 elementor-widget elementor-widget-spacer\" data-id=\"7297b0e9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-69e7574a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"69e7574a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1073ff62\" data-id=\"1073ff62\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7cd2bfd6 elementor-widget elementor-widget-image\" data-id=\"7cd2bfd6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"896\" src=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2026\/06\/giugno_2026-1024x896.jpeg\" class=\"attachment-large size-large wp-image-8751\" alt=\"\" srcset=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2026\/06\/giugno_2026-1024x896.jpeg 1024w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2026\/06\/giugno_2026-300x262.jpeg 300w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2026\/06\/giugno_2026-768x672.jpeg 768w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2026\/06\/giugno_2026-14x12.jpeg 14w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2026\/06\/giugno_2026.jpeg 1085w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-9766f1e\" data-id=\"9766f1e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fcec6b8 elementor-widget elementor-widget-text-editor\" data-id=\"fcec6b8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Giugno 2026<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5d2f297f elementor-widget elementor-widget-heading\" data-id=\"5d2f297f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Sgrossatura aggressiva<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2a3f7b48 elementor-widget elementor-widget-text-editor\" data-id=\"2a3f7b48\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Come spingere sull\u2019impostazione del ciclo di lavoro e sui parametri di taglio per aumentare la competitivit\u00e0 in termini di tempo mantenendo intatta la qualit\u00e0 richiesta.<\/p><p style=\"text-align: right;\"><a href=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2026\/06\/giugno_2026.pdf\" target=\"_blank\" rel=\"noopener\">Vai all&#8217;articolo&#8230;<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-14b704e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"14b704e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-273a6ce\" data-id=\"273a6ce\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dd35077 elementor-widget elementor-widget-image\" data-id=\"dd35077\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"963\" height=\"1024\" src=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2026\/09\/gennaio_2026-963x1024.jpeg\" class=\"attachment-large size-large wp-image-8838\" alt=\"\" srcset=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2026\/09\/gennaio_2026-963x1024.jpeg 963w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2026\/09\/gennaio_2026-282x300.jpeg 282w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2026\/09\/gennaio_2026-768x817.jpeg 768w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2026\/09\/gennaio_2026-11x12.jpeg 11w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2026\/09\/gennaio_2026.jpeg 1040w\" sizes=\"(max-width: 963px) 100vw, 963px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3b739d0\" data-id=\"3b739d0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-201381f elementor-widget elementor-widget-text-editor\" data-id=\"201381f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Gennaio 2026<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5e49bb7 elementor-widget elementor-widget-heading\" data-id=\"5e49bb7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Come l'intelligenza artificiale aiuta le aziende manifatturiere<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3decbb8 elementor-widget elementor-widget-text-editor\" data-id=\"3decbb8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Con questo articolo proseguiamo il monitoraggio del mercato dei software basati sull\u2019intelligenza artificiale che possono supportare le aziende manifatturiere.<\/p><p style=\"text-align: right;\"><a href=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2026\/09\/gennaio_2026.pdf\" target=\"_blank\" rel=\"noopener\">Vai all&#8217;articolo&#8230;<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ff103c3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ff103c3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6e8c55b\" data-id=\"6e8c55b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-40d540a elementor-widget elementor-widget-image\" data-id=\"40d540a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"941\" src=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2026\/02\/dicembre_2025-1024x941.jpeg\" class=\"attachment-large size-large wp-image-8475\" alt=\"\" srcset=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2026\/02\/dicembre_2025-1024x941.jpeg 1024w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2026\/02\/dicembre_2025-300x276.jpeg 300w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2026\/02\/dicembre_2025-768x705.jpeg 768w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2026\/02\/dicembre_2025-1536x1411.jpeg 1536w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2026\/02\/dicembre_2025-13x12.jpeg 13w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2026\/02\/dicembre_2025.jpeg 1634w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-61c414e\" data-id=\"61c414e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-18540e0 elementor-widget elementor-widget-text-editor\" data-id=\"18540e0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Dicembre 2025<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-254839c elementor-widget elementor-widget-heading\" data-id=\"254839c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Skill gap<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-705041a elementor-widget elementor-widget-text-editor\" data-id=\"705041a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Che rapporto hanno i giovani con il settore manifatturiero delle lavorazioni meccaniche?<\/p><p style=\"text-align: right;\"><a href=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2026\/02\/dicembre_2025.pdf\" target=\"_blank\" rel=\"noopener\">Vai all&#8217;articolo&#8230;<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c1548e7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c1548e7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5eef8b3\" data-id=\"5eef8b3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e1b9070 elementor-widget elementor-widget-image\" data-id=\"e1b9070\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"556\" src=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2026\/02\/novembre_2025-1024x556.jpeg\" class=\"attachment-large size-large wp-image-8476\" alt=\"\" srcset=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2026\/02\/novembre_2025-1024x556.jpeg 1024w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2026\/02\/novembre_2025-300x163.jpeg 300w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2026\/02\/novembre_2025-768x417.jpeg 768w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2026\/02\/novembre_2025-18x10.jpeg 18w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2026\/02\/novembre_2025.jpeg 1527w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-213c00c\" data-id=\"213c00c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-add070a elementor-widget elementor-widget-text-editor\" data-id=\"add070a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Novembre 2025<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a208922 elementor-widget elementor-widget-heading\" data-id=\"a208922\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Quando il truciolo scalda l'officina<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b460c97 elementor-widget elementor-widget-text-editor\" data-id=\"b460c97\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Come scoprire e sfruttare il calore perduto delle lavorazioni meccaniche.<\/p><p style=\"text-align: right;\"><a href=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2026\/02\/novembre_2025.pdf\" target=\"_blank\" rel=\"noopener\">Vai all&#8217;articolo&#8230;<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a8e2835 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a8e2835\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4278519\" data-id=\"4278519\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-681ff55 elementor-widget elementor-widget-image\" data-id=\"681ff55\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"763\" src=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2026\/02\/ottobre_2025-1024x763.jpeg\" class=\"attachment-large size-large wp-image-8474\" alt=\"\" srcset=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2026\/02\/ottobre_2025-1024x763.jpeg 1024w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2026\/02\/ottobre_2025-300x223.jpeg 300w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2026\/02\/ottobre_2025-768x572.jpeg 768w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2026\/02\/ottobre_2025-16x12.jpeg 16w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2026\/02\/ottobre_2025.jpeg 1082w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e073996\" data-id=\"e073996\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ef0b211 elementor-widget elementor-widget-text-editor\" data-id=\"ef0b211\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ottobre 2025<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0586c00 elementor-widget elementor-widget-heading\" data-id=\"0586c00\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Microlavorazioni con taglio a getto d'acqua<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2a378a1 elementor-widget elementor-widget-text-editor\" data-id=\"2a378a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Questo articolo ha l\u2019obiettivo di ripercorrere l\u2019evoluzione che il getto d\u2019acqua standard ha avuto verso il microAWJ presso il WJ_Lab del Dipartimento di Meccanica del Politecnico di Milano.<\/p><p style=\"text-align: right;\"><a href=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2026\/02\/ottobre_2025.pdf\" target=\"_blank\" rel=\"noopener\">Vai all&#8217;articolo&#8230;<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-693fc87 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"693fc87\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-ae34e2d\" data-id=\"ae34e2d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d3a3692 elementor-widget elementor-widget-image\" data-id=\"d3a3692\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"455\" height=\"346\" src=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2026\/08\/settembre_2025.jpeg\" class=\"attachment-large size-large wp-image-8829\" alt=\"\" srcset=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2026\/08\/settembre_2025.jpeg 455w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2026\/08\/settembre_2025-300x228.jpeg 300w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2026\/08\/settembre_2025-16x12.jpeg 16w\" sizes=\"(max-width: 455px) 100vw, 455px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-33b6262\" data-id=\"33b6262\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6257fc0 elementor-widget elementor-widget-text-editor\" data-id=\"6257fc0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Settembre 2025<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-28df081 elementor-widget elementor-widget-heading\" data-id=\"28df081\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Tolleranze. Un aiuto a portata di click<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-640e2b3 elementor-widget elementor-widget-text-editor\" data-id=\"640e2b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Quello delle tolleranze \u00e8 un tema complesso, reso ancora pi\u00f9 ostico dalla normale avversione del cervello umano verso ci\u00f2 che \u00e8 ignoto e difficilmente governabile. Ma il digitale pu\u00f2 aiutarci.<\/p><p style=\"text-align: right;\"><a href=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2026\/02\/settembre_2025.pdf\" target=\"_blank\" rel=\"noopener\">Vai all&#8217;articolo&#8230;<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6255c99 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6255c99\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-22ef0e4\" data-id=\"22ef0e4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1c051d4 elementor-widget elementor-widget-image\" data-id=\"1c051d4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"615\" src=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2025\/07\/luglio_2025-1024x615.jpeg\" class=\"attachment-large size-large wp-image-8271\" alt=\"\" srcset=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2025\/07\/luglio_2025-1024x615.jpeg 1024w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2025\/07\/luglio_2025-300x180.jpeg 300w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2025\/07\/luglio_2025-768x462.jpeg 768w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2025\/07\/luglio_2025-18x12.jpeg 18w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2025\/07\/luglio_2025.jpeg 1040w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-44c7d11\" data-id=\"44c7d11\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-afcddaf elementor-widget elementor-widget-text-editor\" data-id=\"afcddaf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Luglio 2025<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-11f5a7b elementor-widget elementor-widget-heading\" data-id=\"11f5a7b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Il Manufacturing al centro della formazione<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8533723 elementor-widget elementor-widget-text-editor\" data-id=\"8533723\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La manifattura in Italia \u00e8 un pilastro fondamentale dell\u2019economia, occupando un sesto della forza lavoro e contribuendo in uguale misura al PIL nazionale<\/p><p style=\"text-align: right;\"><a href=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2025\/07\/luglio_2025.pdf\" target=\"_blank\" rel=\"noopener\">Vai all&#8217;articolo&#8230;<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5bd0478 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5bd0478\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-a9fabff\" data-id=\"a9fabff\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f1c69c0 elementor-widget elementor-widget-image\" data-id=\"f1c69c0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"935\" height=\"874\" src=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2025\/07\/giugno_2025.jpeg\" class=\"attachment-large size-large wp-image-8279\" alt=\"\" srcset=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2025\/07\/giugno_2025.jpeg 935w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2025\/07\/giugno_2025-300x280.jpeg 300w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2025\/07\/giugno_2025-768x718.jpeg 768w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2025\/07\/giugno_2025-13x12.jpeg 13w\" sizes=\"(max-width: 935px) 100vw, 935px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-8388f7b\" data-id=\"8388f7b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-290104b elementor-widget elementor-widget-text-editor\" data-id=\"290104b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Giugno 2025<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1b253b6 elementor-widget elementor-widget-heading\" data-id=\"1b253b6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"> Il gemello digitale del getto d\u2019acqua<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-51c4fac elementor-widget elementor-widget-text-editor\" data-id=\"51c4fac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Il taglio a getto d\u2019acqua \u00e8 un processo di produzione straordinario, con un\u2019ampia gamma di applicazioni avanzate in molti settori industriali, come quello meccanico, <br \/>aeronautico, biomedico, elettronico, del marmo e della pietra, dei materiali compositi, del vetro, della ceramica&#8230;<\/p><p style=\"text-align: right;\"><a href=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2025\/07\/giugno_2025.pdf\" target=\"_blank\" rel=\"noopener\">Vai all&#8217;articolo&#8230;<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-43b64d8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"43b64d8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-45a181d\" data-id=\"45a181d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b7b2696 elementor-widget elementor-widget-image\" data-id=\"b7b2696\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"593\" src=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2025\/05\/maggio_2025-1024x593.jpeg\" class=\"attachment-large size-large wp-image-8199\" alt=\"\" srcset=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2025\/05\/maggio_2025-1024x593.jpeg 1024w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2025\/05\/maggio_2025-300x174.jpeg 300w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2025\/05\/maggio_2025-768x445.jpeg 768w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2025\/05\/maggio_2025-18x10.jpeg 18w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2025\/05\/maggio_2025.jpeg 1529w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-10f01bc\" data-id=\"10f01bc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d25e8ee elementor-widget elementor-widget-text-editor\" data-id=\"d25e8ee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Maggio 2025<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5343532 elementor-widget elementor-widget-heading\" data-id=\"5343532\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Attenzione alle tolleranze!<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-267b2b4 elementor-widget elementor-widget-text-editor\" data-id=\"267b2b4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tCon questo articolo si vuole iniziare una raccolta di alcune regole di base per assegnare correttamente le tolleranze in un disegno tecnico in vista delle lavorazioni meccaniche.<p style=\"text-align: right;\"><a href=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2025\/05\/maggio_2025.pdf\" target=\"_blank\" rel=\"noopener\">Vai all&#8217;articolo&#8230;<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7f51029 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7f51029\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6280845\" data-id=\"6280845\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1dd5dc0 elementor-widget elementor-widget-image\" data-id=\"1dd5dc0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"759\" src=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2025\/04\/aprile_2025-1024x759.png\" class=\"attachment-large size-large wp-image-8126\" alt=\"\" srcset=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2025\/04\/aprile_2025-1024x759.png 1024w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2025\/04\/aprile_2025-300x222.png 300w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2025\/04\/aprile_2025-768x569.png 768w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2025\/04\/aprile_2025-16x12.png 16w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2025\/04\/aprile_2025.png 1196w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1360cad\" data-id=\"1360cad\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2b3f504 elementor-widget elementor-widget-text-editor\" data-id=\"2b3f504\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Aprile 2025<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dfb52dc elementor-widget elementor-widget-heading\" data-id=\"dfb52dc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Energia specifica: La carta d\u2019identit\u00e0 energetica dei processi<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4cccb57 elementor-widget elementor-widget-text-editor\" data-id=\"4cccb57\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>In questo articolo, si riportano esempi di processi operanti secondo diversi principi fisici, a conferma che la trattazione energetica basata sull\u2019exergia (energia) specifica ha valore generale.<\/p><p style=\"text-align: right;\"><a href=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2025\/04\/aprile_2025.pdf\" target=\"_blank\" rel=\"noopener\">Vai all&#8217;articolo&#8230;<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-31a52b7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"31a52b7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c74b944\" data-id=\"c74b944\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4572e36 elementor-widget elementor-widget-image\" data-id=\"4572e36\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"782\" src=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2024\/12\/copertina_novembre_2024-1024x782.jpg\" class=\"attachment-large size-large wp-image-7881\" alt=\"\" srcset=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2024\/12\/copertina_novembre_2024-1024x782.jpg 1024w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2024\/12\/copertina_novembre_2024-300x229.jpg 300w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2024\/12\/copertina_novembre_2024-768x586.jpg 768w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2024\/12\/copertina_novembre_2024-16x12.jpg 16w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2024\/12\/copertina_novembre_2024.jpg 1339w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-620481c\" data-id=\"620481c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5e4570f elementor-widget elementor-widget-text-editor\" data-id=\"5e4570f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Marzo 2025<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1373f65 elementor-widget elementor-widget-heading\" data-id=\"1373f65\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Scegliere i processi di lavorazione in funzione del consumo energetico<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-160c8ab elementor-widget elementor-widget-text-editor\" data-id=\"160c8ab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Questo articolo prosegue l\u2019analisi energetica delle lavorazioni di fresatura gi\u00e0 affrontato con l\u2019articolo \u201c<strong>L\u2019energia in tornitura e fresatura<\/strong>\u201d, pubblicato su Macchine Utensili di novembre 2024 e l\u2019articolo \u201c<strong>Ottimizzare l\u2019energia in fresatura<\/strong>\u201d, pubblicato su Macchine Utensili di dicembre 2024<\/p><p style=\"text-align: right;\"><a href=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2025\/03\/marzo_2025.pdf\" target=\"_blank\" rel=\"noopener\">Vai all&#8217;articolo&#8230;<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-56b4357 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"56b4357\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-58762e2\" data-id=\"58762e2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-831e3b1 elementor-widget elementor-widget-image\" data-id=\"831e3b1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"420\" height=\"420\" src=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2025\/03\/febbraio_2025.png\" class=\"attachment-large size-large wp-image-8063\" alt=\"\" srcset=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2025\/03\/febbraio_2025.png 420w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2025\/03\/febbraio_2025-300x300.png 300w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2025\/03\/febbraio_2025-150x150.png 150w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2025\/03\/febbraio_2025-12x12.png 12w\" sizes=\"(max-width: 420px) 100vw, 420px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6ff8896\" data-id=\"6ff8896\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4f95054 elementor-widget elementor-widget-text-editor\" data-id=\"4f95054\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Febbraio 2025<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-62498e8 elementor-widget elementor-widget-heading\" data-id=\"62498e8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"> Il runout nella fresatura<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-38e9f22 elementor-widget elementor-widget-text-editor\" data-id=\"38e9f22\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Che cos\u2019\u00e8 il <strong>runout<\/strong> della fresa, come misurarlo e come prevederne gli effetti. Questo articolo descrive una <strong>procedura ripetibile<\/strong> in grado di rilevare il runout dell\u2019utensile a bordo di un centro di <strong>lavorazione di precisione<\/strong>, tenendo conto sia degli errori di rotondit\u00e0 dell\u2019utensile sia degli <strong>errori di centraggio<\/strong> tra utensile e portautensile.<\/p><p style=\"text-align: right;\"><a href=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2025\/03\/febbraio_2025.pdf\" target=\"_blank\" rel=\"noopener\">Vai all&#8217;articolo&#8230;<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8e6c563 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8e6c563\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-d3d5eef\" data-id=\"d3d5eef\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3746a8d elementor-widget elementor-widget-image\" data-id=\"3746a8d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"801\" height=\"565\" src=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2025\/01\/gennaio_2025.png\" class=\"attachment-large size-large wp-image-7969\" alt=\"\" srcset=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2025\/01\/gennaio_2025.png 801w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2025\/01\/gennaio_2025-300x212.png 300w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2025\/01\/gennaio_2025-768x542.png 768w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2025\/01\/gennaio_2025-18x12.png 18w\" sizes=\"(max-width: 801px) 100vw, 801px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c11fba4\" data-id=\"c11fba4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bb15ce9 elementor-widget elementor-widget-text-editor\" data-id=\"bb15ce9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Gennaio 2025<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bfbc278 elementor-widget elementor-widget-heading\" data-id=\"bfbc278\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Potenza, energia e durata utensile in fresatura trocoidale<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-204d7c4 elementor-widget elementor-widget-text-editor\" data-id=\"204d7c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Questo articolo prosegue l\u2019analisi energetica delle lavorazioni di fresatura<br \/>gi\u00e0 affrontato con l\u2019articolo \u201c<strong>L\u2019energia in tornitura e fresatura<\/strong>\u201d, pubblicato su Macchine Utensili di novembre 2024 e l\u2019articolo \u201c<strong>Ottimizzare l\u2019energia in fresatura<\/strong>\u201d, pubblicato su Macchine Utensili di dicembre 2024<\/p><p style=\"text-align: right;\"><a href=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2025\/04\/gennaio_2025_erratacorrige.pdf\" target=\"_blank\" rel=\"noopener\">Vai all&#8217;articolo&#8230;<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c95b5fb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c95b5fb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b19067a\" data-id=\"b19067a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3221e09 elementor-widget elementor-widget-image\" data-id=\"3221e09\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"782\" src=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2024\/12\/copertina_novembre_2024-1024x782.jpg\" class=\"attachment-large size-large wp-image-7881\" alt=\"\" srcset=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2024\/12\/copertina_novembre_2024-1024x782.jpg 1024w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2024\/12\/copertina_novembre_2024-300x229.jpg 300w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2024\/12\/copertina_novembre_2024-768x586.jpg 768w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2024\/12\/copertina_novembre_2024-16x12.jpg 16w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2024\/12\/copertina_novembre_2024.jpg 1339w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-94dafc2\" data-id=\"94dafc2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e287f68 elementor-widget elementor-widget-text-editor\" data-id=\"e287f68\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Dicembre 2024<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-13db60c elementor-widget elementor-widget-heading\" data-id=\"13db60c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ottimizzare l\u2019energia in fresatura<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-afe110b elementor-widget elementor-widget-text-editor\" data-id=\"afe110b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Questo articolo vuole fornire alcuni spunti di riflessione utili alle aziende operanti nel settore della fresatura per pensare o ripensare alle strategie e agli utensili da usare per ottenere un risparmio energetico.<\/p><p style=\"text-align: right;\"><a href=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2024\/12\/novembre_2024.pdf\" target=\"_blank\" rel=\"noopener\">Vai all&#8217;articolo&#8230;<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-56b7ed0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"56b7ed0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-ea3d505\" data-id=\"ea3d505\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4068aff elementor-widget elementor-widget-image\" data-id=\"4068aff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"856\" src=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2024\/12\/copertina_ottobre1_2024-1024x856.jpg\" class=\"attachment-large size-large wp-image-7882\" alt=\"\" srcset=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2024\/12\/copertina_ottobre1_2024-1024x856.jpg 1024w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2024\/12\/copertina_ottobre1_2024-300x251.jpg 300w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2024\/12\/copertina_ottobre1_2024-768x642.jpg 768w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2024\/12\/copertina_ottobre1_2024-1536x1284.jpg 1536w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2024\/12\/copertina_ottobre1_2024-14x12.jpg 14w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2024\/12\/copertina_ottobre1_2024.jpg 1618w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-ab09280\" data-id=\"ab09280\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-51d8817 elementor-widget elementor-widget-text-editor\" data-id=\"51d8817\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Novembre 2024<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4553777 elementor-widget elementor-widget-heading\" data-id=\"4553777\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">L\u2019energia in tornitura e fresatura<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a78c156 elementor-widget elementor-widget-text-editor\" data-id=\"a78c156\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Questo articolo fornisce la definizione della pressione di taglio e mostra come sia un parametro chiave per la potenza e l\u2019energia richiesta per le lavorazioni di tornitura e fresatura, ma, pi\u00f9 in generale, per tutte le operazioni di asportazione di truciolo.<\/p><p style=\"text-align: right;\"><a href=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2024\/12\/ottobre1_2024.pdf\" target=\"_blank\" rel=\"noopener\">Vai all&#8217;articolo&#8230;<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-29ec671 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"29ec671\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-13eb9ea\" data-id=\"13eb9ea\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1e8fe44 elementor-widget elementor-widget-image\" data-id=\"1e8fe44\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2024\/10\/ottobre_2024-e1729086124253-1024x1024.jpg\" class=\"attachment-large size-large wp-image-7767\" alt=\"\" srcset=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2024\/10\/ottobre_2024-e1729086124253-1024x1024.jpg 1024w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2024\/10\/ottobre_2024-e1729086124253-300x300.jpg 300w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2024\/10\/ottobre_2024-e1729086124253-150x150.jpg 150w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2024\/10\/ottobre_2024-e1729086124253-768x768.jpg 768w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2024\/10\/ottobre_2024-e1729086124253-1536x1536.jpg 1536w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2024\/10\/ottobre_2024-e1729086124253-12x12.jpg 12w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2024\/10\/ottobre_2024-e1729086124253-600x600.jpg 600w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2024\/10\/ottobre_2024-e1729086124253.jpg 1637w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-8ad8c30\" data-id=\"8ad8c30\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3854995 elementor-widget elementor-widget-text-editor\" data-id=\"3854995\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ottobre 2024<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e7895ca elementor-widget elementor-widget-heading\" data-id=\"e7895ca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Le tensioni residue nelle lavorazioni meccaniche<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-71a5235 elementor-widget elementor-widget-text-editor\" data-id=\"71a5235\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Attraverso una schematizzazione del problema delle tensioni residue di origine termica che si generano durante il raffreddamento di un grezzo di fonderia in sabbia, vengono fornite alcune semplici equazioni in grado di cogliere la fisica del fenomeno.<\/p><p style=\"text-align: right;\"><a href=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2024\/10\/ottobre_2024.pdf\" target=\"_blank\" rel=\"noopener\">Vai all&#8217;articolo&#8230;<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9ef64ae elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9ef64ae\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-09b1d25\" data-id=\"09b1d25\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-679277e elementor-widget elementor-widget-image\" data-id=\"679277e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"795\" src=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2024\/09\/settembre2_2024-1024x795.png\" class=\"attachment-large size-large wp-image-7416\" alt=\"\" srcset=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2024\/09\/settembre2_2024-1024x795.png 1024w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2024\/09\/settembre2_2024-300x233.png 300w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2024\/09\/settembre2_2024-768x596.png 768w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2024\/09\/settembre2_2024-15x12.png 15w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2024\/09\/settembre2_2024.png 1388w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-addedd8\" data-id=\"addedd8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-28d0a5c elementor-widget elementor-widget-text-editor\" data-id=\"28d0a5c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Settembre 2024<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8a16381 elementor-widget elementor-widget-heading\" data-id=\"8a16381\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">La Visione Artificiale nel Machining<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0ce3055 elementor-widget elementor-widget-text-editor\" data-id=\"0ce3055\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La visione artificiale (o computer vision o machine vision) \u00e8 un campo dell&#8217;intelligenza artificiale (IA) che permette ai computer di ricavare informazioni significative da immagini digitali, video e altri input visivi e intraprendere azioni o formulare delle segnalazioni sulla base di tali informazioni. Se l&#8217;IA in generale permette ai computer di pensare, la computer vision permette loro di vedere, osservare e capire.<\/p><p style=\"text-align: right;\"><a href=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2024\/09\/settembre2_2024.pdf\" target=\"_blank\" rel=\"noopener\">Vai all&#8217;articolo&#8230;<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ff47f25 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ff47f25\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c64d56d\" data-id=\"c64d56d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-12061e5 elementor-widget elementor-widget-image\" data-id=\"12061e5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2024\/09\/settembre1_2024.png\" class=\"attachment-large size-large wp-image-7417\" alt=\"\" srcset=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2024\/09\/settembre1_2024.png 1025w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2024\/09\/settembre1_2024-300x300.png 300w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2024\/09\/settembre1_2024-150x150.png 150w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2024\/09\/settembre1_2024-768x768.png 768w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2024\/09\/settembre1_2024-12x12.png 12w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2024\/09\/settembre1_2024-600x600.png 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-d3e16e0\" data-id=\"d3e16e0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ce1ef01 elementor-widget elementor-widget-text-editor\" data-id=\"ce1ef01\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Settembre 2024<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f97c55c elementor-widget elementor-widget-heading\" data-id=\"f97c55c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Il machining al Politecnico di Milano<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b396070 elementor-widget elementor-widget-text-editor\" data-id=\"b396070\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Questo articolo fa un quadro degli insegnamenti disponibili per gli studenti universitari che frequentano il Corso di Studi in Ingegneria Meccanica del Politecnico di Milano, in modo che le aziende che si occupano di processi di asportazione di truciolo possano avere un\u2019idea chiara delle competenze che il Corso fornisce ai propri allievi per rispondere alle esigenze del settore.<\/p><p style=\"text-align: right;\"><a href=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2024\/09\/settembre1_2024.pdf\" target=\"_blank\" rel=\"noopener\">Vai all&#8217;articolo&#8230;<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1a41822 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1a41822\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1482115\" data-id=\"1482115\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5b2e54a elementor-widget elementor-widget-image\" data-id=\"5b2e54a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2024\/09\/settembre_2024-1024x1024.jpg\" class=\"attachment-large size-large wp-image-7273\" alt=\"\" srcset=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2024\/09\/settembre_2024-1024x1024.jpg 1024w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2024\/09\/settembre_2024-300x300.jpg 300w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2024\/09\/settembre_2024-150x150.jpg 150w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2024\/09\/settembre_2024-768x768.jpg 768w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2024\/09\/settembre_2024-1536x1536.jpg 1536w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2024\/09\/settembre_2024-2048x2048.jpg 2048w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2024\/09\/settembre_2024-12x12.jpg 12w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2024\/09\/settembre_2024-600x600.jpg 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b088b5f\" data-id=\"b088b5f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-04ad3fd elementor-widget elementor-widget-text-editor\" data-id=\"04ad3fd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Settembre 2024<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7ad2479 elementor-widget elementor-widget-heading\" data-id=\"7ad2479\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Le complessit\u00e0 di produrre un pezzo complesso al primo tentativo<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8672ebf elementor-widget elementor-widget-text-editor\" data-id=\"8672ebf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Lo scorso 17 Maggio si \u00e8 tenuto presso il Dipartimento di Meccanica del Politecnico di Milano il primo Workshop dell&#8217;anno di PoliMill. Durante l&#8217;evento sono stati presentati tutti i passi e i mezzi necessari alla realizazzione di un componente complesso al primo colpo!<\/p><p style=\"text-align: right;\"><a href=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2024\/09\/settembre_2024.pdf\" target=\"_blank\" rel=\"noopener\">Vai all&#8217;articolo&#8230;<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-afe5a22 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"afe5a22\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4c2495d\" data-id=\"4c2495d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-66e8190 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"66e8190\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bdd9858 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bdd9858\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-493b2da\" data-id=\"493b2da\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-88cbb8f elementor-widget elementor-widget-image\" data-id=\"88cbb8f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"864\" src=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2024\/07\/giugno_2024-1024x864.jpg\" class=\"attachment-large size-large wp-image-7239\" alt=\"\" srcset=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2024\/07\/giugno_2024-1024x864.jpg 1024w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2024\/07\/giugno_2024-300x253.jpg 300w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2024\/07\/giugno_2024-768x648.jpg 768w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2024\/07\/giugno_2024-1536x1297.jpg 1536w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2024\/07\/giugno_2024-14x12.jpg 14w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2024\/07\/giugno_2024.jpg 1636w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-055dfd8\" data-id=\"055dfd8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b81b306 elementor-widget elementor-widget-text-editor\" data-id=\"b81b306\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Giugno 2024<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-05c1d57 elementor-widget elementor-widget-heading\" data-id=\"05c1d57\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">E se volessimo usare l\u2019intelligenza artificiale in officina?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-31d8891 elementor-widget elementor-widget-text-editor\" data-id=\"31d8891\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Questo articolo completa la trattazione sull\u2019applicazione dell\u2019intelligenza artificiale (IA) iniziata con l\u2019articolo <a href=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2024\/05\/maggio_2024.pdf\" target=\"_blank\" rel=\"noopener\">\u201cL\u2019intelligenza artificiale nel machining\u201d<\/a>.<br \/>Mentre il primo articolo aveva lo scopo di porre le basi storiche e tecniche dell\u2019intelligenza artificiale in senso lato, questo articolo riporta alcuni esempi di applicazione dell\u2019IA nel machining.<\/p><p style=\"text-align: right;\"><a href=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2024\/07\/giugno_2024.pdf\" target=\"_blank\" rel=\"noopener\">Vai all&#8217;articolo&#8230;<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7eeaec6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7eeaec6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e2f91aa\" data-id=\"e2f91aa\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a6da9a7 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"a6da9a7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-968b718 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"968b718\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-fc642ee\" data-id=\"fc642ee\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5d2e986 elementor-widget elementor-widget-image\" data-id=\"5d2e986\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"936\" height=\"774\" src=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2024\/05\/copertina_maggio_2024.jpg\" class=\"attachment-large size-large wp-image-7075\" alt=\"\" srcset=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2024\/05\/copertina_maggio_2024.jpg 936w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2024\/05\/copertina_maggio_2024-300x248.jpg 300w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2024\/05\/copertina_maggio_2024-768x635.jpg 768w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2024\/05\/copertina_maggio_2024-15x12.jpg 15w\" sizes=\"(max-width: 936px) 100vw, 936px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-d1d046e\" data-id=\"d1d046e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7a3a33e elementor-widget elementor-widget-text-editor\" data-id=\"7a3a33e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Maggio 2024<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fbc694a elementor-widget elementor-widget-heading\" data-id=\"fbc694a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">L'intelligenza artificiale nel machining<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-10a5c92 elementor-widget elementor-widget-text-editor\" data-id=\"10a5c92\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La pianificazione e la preparazione del processo di lavorazione hanno un ruolo chiave nella lavorazione in quanto parte importante della produzione industriale.<br \/>Ora i nuovi sistemi di intelligenza artificiale possono contribuire e supportare la pianificazione del processo per ridurre i tempi e ottenere risultati ottimali.<\/p><p style=\"text-align: right;\"><a href=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2024\/05\/maggio_2024.pdf\" target=\"_blank\" rel=\"noopener\">Vai all&#8217;articolo&#8230;<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ec54cc2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ec54cc2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fd70d3f\" data-id=\"fd70d3f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c1fa73a elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"c1fa73a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-db90058 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"db90058\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-a4b5d75\" data-id=\"a4b5d75\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7d89060 elementor-widget elementor-widget-image\" data-id=\"7d89060\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"753\" height=\"673\" src=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2023\/05\/L1.004-Power-and-torque-curve-Okuma-Genos-M460V.png\" class=\"attachment-large size-large wp-image-3311\" alt=\"\" srcset=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2023\/05\/L1.004-Power-and-torque-curve-Okuma-Genos-M460V.png 753w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2023\/05\/L1.004-Power-and-torque-curve-Okuma-Genos-M460V-300x268.png 300w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2023\/05\/L1.004-Power-and-torque-curve-Okuma-Genos-M460V-13x12.png 13w\" sizes=\"(max-width: 753px) 100vw, 753px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-efb2e66\" data-id=\"efb2e66\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f04cd6c elementor-widget elementor-widget-text-editor\" data-id=\"f04cd6c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Marzo 2024<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-84ed9b3 elementor-widget elementor-widget-heading\" data-id=\"84ed9b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Parametri di taglio, coppia e potenza del mandrino<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8460bfe elementor-widget elementor-widget-text-editor\" data-id=\"8460bfe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Questo articolo delinea i passaggi da seguire nella scelta dei parametri di fresatura in funzione delle caratteristiche di coppia e potenza del mandrino della macchina che si ha a disposizione.<\/p><p style=\"text-align: right;\"><a href=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2024\/03\/marzo_2024.pdf\" target=\"_blank\" rel=\"noopener\">Vai all&#8217;articolo&#8230;<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3f23cb4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3f23cb4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0f3fdc6\" data-id=\"0f3fdc6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-46607ae elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"46607ae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-844a3a3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"844a3a3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-0167872\" data-id=\"0167872\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b8b2867 elementor-widget elementor-widget-image\" data-id=\"b8b2867\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2023\/11\/dsc_5591-migliorato-nr-1024x683.jpg\" class=\"attachment-large size-large wp-image-5613\" alt=\"\" srcset=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2023\/11\/dsc_5591-migliorato-nr-1024x683.jpg 1024w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2023\/11\/dsc_5591-migliorato-nr-300x200.jpg 300w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2023\/11\/dsc_5591-migliorato-nr-768x512.jpg 768w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2023\/11\/dsc_5591-migliorato-nr-1536x1024.jpg 1536w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2023\/11\/dsc_5591-migliorato-nr-2048x1365.jpg 2048w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2023\/11\/dsc_5591-migliorato-nr-18x12.jpg 18w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c402daf\" data-id=\"c402daf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-db7b3d4 elementor-widget elementor-widget-text-editor\" data-id=\"db7b3d4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Febbraio 2024<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-77dcd8d elementor-widget elementor-widget-heading\" data-id=\"77dcd8d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">La tradizione incontra il futuro<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-733df3b elementor-widget elementor-widget-text-editor\" data-id=\"733df3b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La digitalizzazione e la fresatura di stampi per elettrodi per celle a combustile al centro del recente workshop svoltosi presso il Dipartimento di Meccanica del Politecnico di Milano, che ha visto la partecipazione di partner qualificati e di numerosi visitatori.<\/p><p style=\"text-align: right;\"><a href=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2024\/02\/febbraio2_2024.pdf\" target=\"_blank\" rel=\"noopener\">Vai all&#8217;articolo&#8230;<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b0acffb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b0acffb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-dcdee1d\" data-id=\"dcdee1d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5116d27 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"5116d27\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cf16db7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cf16db7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5474cc8\" data-id=\"5474cc8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d72fc49 elementor-widget elementor-widget-image\" data-id=\"d72fc49\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2024\/02\/DSC_5323-min-scaled-1-1024x683.jpg\" class=\"attachment-large size-large wp-image-6072\" alt=\"\" srcset=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2024\/02\/DSC_5323-min-scaled-1-1024x683.jpg 1024w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2024\/02\/DSC_5323-min-scaled-1-300x200.jpg 300w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2024\/02\/DSC_5323-min-scaled-1-768x512.jpg 768w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2024\/02\/DSC_5323-min-scaled-1-1536x1024.jpg 1536w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2024\/02\/DSC_5323-min-scaled-1-2048x1366.jpg 2048w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2024\/02\/DSC_5323-min-scaled-1-18x12.jpg 18w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-18814f3\" data-id=\"18814f3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f3c9027 elementor-widget elementor-widget-text-editor\" data-id=\"f3c9027\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Febbraio 2024<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0f3d45c elementor-widget elementor-widget-heading\" data-id=\"0f3d45c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">PoliMill: Learning by Doing<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f6b7701 elementor-widget elementor-widget-text-editor\" data-id=\"f6b7701\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Un laboratorio di alta formazione nell\u2019ambito dell\u2019asportazione di truciolo per i giovani ingegneri del futuro, un punto di aggregazione per realt\u00e0 aziendali, un centro di ricerca che ha come scopo la digitalizzazione e automazione del manifatturiero.<\/p><p style=\"text-align: right;\"><a href=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2024\/02\/febbraio1_2024.pdf\" target=\"_blank\" rel=\"noopener\">Vai all&#8217;articolo&#8230;<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2d7f36d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2d7f36d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e38c330\" data-id=\"e38c330\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-674e455 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"674e455\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cf439b9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cf439b9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-092629a\" data-id=\"092629a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d4aa782 elementor-widget elementor-widget-image\" data-id=\"d4aa782\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"712\" src=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2024\/02\/febbraio_2024-1024x712.png\" class=\"attachment-large size-large wp-image-6039\" alt=\"\" srcset=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2024\/02\/febbraio_2024-1024x712.png 1024w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2024\/02\/febbraio_2024-300x208.png 300w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2024\/02\/febbraio_2024-768x534.png 768w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2024\/02\/febbraio_2024-18x12.png 18w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2024\/02\/febbraio_2024.png 1118w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-043eebb\" data-id=\"043eebb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c5c02c2 elementor-widget elementor-widget-text-editor\" data-id=\"c5c02c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Febbraio 2024<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cbe8341 elementor-widget elementor-widget-heading\" data-id=\"cbe8341\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Il micron unisce il mondo<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-97029b3 elementor-widget elementor-widget-text-editor\" data-id=\"97029b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Era il 2009 quando, dopo aver avviato le attivit\u00e0 di MI_crolab, il Laboratorio di Microlavorazioni Meccaniche del Dipartimento di Meccanica del Politecnico di Milano, decidemmo di approcciare la comunit\u00e0 internazionale delle microlavorazioni partecipando alla conferenza di settore che meglio rappresentava la nostra linea di ricerca, 4M (Multi-Material Micro Manufacturing Conference).<\/p><p style=\"text-align: right;\"><a href=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2024\/02\/febbraio_2024.pdf\" target=\"_blank\" rel=\"noopener\">Vai all&#8217;articolo&#8230;<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0562ebf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0562ebf\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8f740b8\" data-id=\"8f740b8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8b376a4 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"8b376a4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b879de4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b879de4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-eb162f1\" data-id=\"eb162f1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d44c4d0 elementor-widget elementor-widget-image\" data-id=\"d44c4d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"575\" height=\"557\" src=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2024\/02\/gennaio_2024.png\" class=\"attachment-large size-large wp-image-6056\" alt=\"\" srcset=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2024\/02\/gennaio_2024.png 575w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2024\/02\/gennaio_2024-300x291.png 300w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2024\/02\/gennaio_2024-12x12.png 12w\" sizes=\"(max-width: 575px) 100vw, 575px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3735e81\" data-id=\"3735e81\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e42e420 elementor-widget elementor-widget-text-editor\" data-id=\"e42e420\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Gennaio 2024<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ea22227 elementor-widget elementor-widget-heading\" data-id=\"ea22227\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Il primo motore<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-391c846 elementor-widget elementor-widget-text-editor\" data-id=\"391c846\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Mondo manifatturiero, tecnologia meccanica, materiali: dal concetto astratto al manufatto, seguendo un percorso che parla della storia dell\u2019uomo e della civilt\u00e0.<\/p><p style=\"text-align: right;\"><a href=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2024\/02\/gennaio_2024.pdf\" target=\"_blank\" rel=\"noopener\">Vai all&#8217;articolo&#8230;<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-48cb591 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"48cb591\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fa6b6d0\" data-id=\"fa6b6d0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-021bd96 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"021bd96\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0b2c509 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0b2c509\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f35401e\" data-id=\"f35401e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dde8904 elementor-widget elementor-widget-image\" data-id=\"dde8904\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2023\/10\/dsc_5453-migliorato-nr-1024x683.jpg\" class=\"attachment-large size-large wp-image-5562\" alt=\"\" srcset=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2023\/10\/dsc_5453-migliorato-nr-1024x683.jpg 1024w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2023\/10\/dsc_5453-migliorato-nr-300x200.jpg 300w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2023\/10\/dsc_5453-migliorato-nr-768x512.jpg 768w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2023\/10\/dsc_5453-migliorato-nr-1536x1024.jpg 1536w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2023\/10\/dsc_5453-migliorato-nr-2048x1365.jpg 2048w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2023\/10\/dsc_5453-migliorato-nr-18x12.jpg 18w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-fc2ee1a\" data-id=\"fc2ee1a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cc8f2bd elementor-widget elementor-widget-text-editor\" data-id=\"cc8f2bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ottobre 2023<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ca125df elementor-widget elementor-widget-heading\" data-id=\"ca125df\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Words are not enough<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8983af1 elementor-widget elementor-widget-text-editor\" data-id=\"8983af1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Lo scopo dell&#8217;aggiornamento tecnologico proposto da PoliMill e MADE si basa sulla concretezza, seguendo un programma completo, dal progetto al pezzo finito e alla sua validazione.<\/p><p style=\"text-align: right;\"><a href=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2023\/10\/ottobre_2023.pdf\" target=\"_blank\" rel=\"noopener\">Vai all&#8217;articolo&#8230;<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c50e422 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c50e422\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-903a6a6\" data-id=\"903a6a6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bc987bd elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"bc987bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ef4fcf3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ef4fcf3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7dea731\" data-id=\"7dea731\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-17f59a7 elementor-widget elementor-widget-image\" data-id=\"17f59a7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2023\/10\/dsc_5461-migliorato-nr-1024x683.jpg\" class=\"attachment-large size-large wp-image-5544\" alt=\"\" srcset=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2023\/10\/dsc_5461-migliorato-nr-1024x683.jpg 1024w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2023\/10\/dsc_5461-migliorato-nr-300x200.jpg 300w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2023\/10\/dsc_5461-migliorato-nr-768x512.jpg 768w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2023\/10\/dsc_5461-migliorato-nr-1536x1024.jpg 1536w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2023\/10\/dsc_5461-migliorato-nr-2048x1365.jpg 2048w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2023\/10\/dsc_5461-migliorato-nr-18x12.jpg 18w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-9dec440\" data-id=\"9dec440\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2e9e063 elementor-widget elementor-widget-text-editor\" data-id=\"2e9e063\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Settembre 2023<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-98949ba elementor-widget elementor-widget-heading\" data-id=\"98949ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Milling between the past and the future<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9819b29 elementor-widget elementor-widget-text-editor\" data-id=\"9819b29\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Manufacturing and machining processes have underpinned the development of Western society over the past 200 years. The evolution of the manufacturing sector has kept pace with the major technological developments of the last century by integrating them into its processes and machinery.<\/p><p style=\"text-align: right;\"><a href=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2023\/10\/settembre_2023.pdf\" target=\"_blank\" rel=\"noopener\">Vai all&#8217;articolo&#8230;<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b6f5c8d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b6f5c8d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-817fb98\" data-id=\"817fb98\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2d0f844 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"2d0f844\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-caa89b8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"caa89b8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6bc2ec7\" data-id=\"6bc2ec7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-95635c6 elementor-widget elementor-widget-image\" data-id=\"95635c6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2023\/05\/DSC_4948-min-1024x683.jpg\" class=\"attachment-large size-large wp-image-3258\" alt=\"\" srcset=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2023\/05\/DSC_4948-min-1024x683.jpg 1024w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2023\/05\/DSC_4948-min-300x200.jpg 300w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2023\/05\/DSC_4948-min-768x512.jpg 768w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2023\/05\/DSC_4948-min-1536x1024.jpg 1536w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2023\/05\/DSC_4948-min-2048x1365.jpg 2048w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2023\/05\/DSC_4948-min-18x12.jpg 18w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-0fb283e\" data-id=\"0fb283e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8a78b3a elementor-widget elementor-widget-text-editor\" data-id=\"8a78b3a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Maggio 2023<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-31420c6 elementor-widget elementor-widget-heading\" data-id=\"31420c6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Accompanying change<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3f8cf50 elementor-widget elementor-widget-text-editor\" data-id=\"3f8cf50\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>L&#8217;evoluzione tecnologica, la scienza dei materiali, ma anche le aspettative (o esigenze) del mercato stanno spingendo il comparto manifatturiero italiano verso il cambiamento, rendendolo sempre pi\u00f9 interessante a livello sia nazionale che internazionale.<\/p><p style=\"text-align: right;\"><a href=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2023\/05\/maggio_2023.pdf\" target=\"_blank\" rel=\"noopener\">Vai all&#8217;articolo&#8230;<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ac06da3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ac06da3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d183538\" data-id=\"d183538\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e242f13 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"e242f13\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5c8977d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5c8977d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-11e3eca\" data-id=\"11e3eca\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d4cc113 elementor-widget elementor-widget-image\" data-id=\"d4cc113\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2022\/12\/DSC_4583-1-1024x682.jpg\" class=\"attachment-large size-large wp-image-2064\" alt=\"\" srcset=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2022\/12\/DSC_4583-1-1024x682.jpg 1024w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2022\/12\/DSC_4583-1-300x200.jpg 300w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2022\/12\/DSC_4583-1-768x511.jpg 768w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2022\/12\/DSC_4583-1-1536x1023.jpg 1536w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2022\/12\/DSC_4583-1-2048x1364.jpg 2048w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2022\/12\/DSC_4583-1-18x12.jpg 18w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-afb566d\" data-id=\"afb566d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-83466ff elementor-widget elementor-widget-text-editor\" data-id=\"83466ff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Marzo 2023<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dbe811e elementor-widget elementor-widget-heading\" data-id=\"dbe811e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Accompanying change<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-035ba4b elementor-widget elementor-widget-text-editor\" data-id=\"035ba4b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>The manufacturing sector. Research. The responsibility of training tomorrow's technicians. And an eye on the digitisation process. A talk with Prof. Massimiliano Annoni, Politecnico di Milano.<\/p><p style=\"text-align: right;\"><a href=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2023\/03\/marzo1_2023.pdf\" target=\"_blank\" rel=\"noopener\">Vai all&#8217;articolo&#8230;<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2cccd8a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2cccd8a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f3938ab\" data-id=\"f3938ab\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e36a1b8 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"e36a1b8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-30f7257 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"30f7257\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-704a458\" data-id=\"704a458\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ac2545d elementor-widget elementor-widget-image\" data-id=\"ac2545d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1705\" src=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2022\/12\/DSC_4614-1-scaled.jpg\" class=\"attachment-full size-full wp-image-2069\" alt=\"\" srcset=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2022\/12\/DSC_4614-1-scaled.jpg 2560w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2022\/12\/DSC_4614-1-300x200.jpg 300w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2022\/12\/DSC_4614-1-1024x682.jpg 1024w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2022\/12\/DSC_4614-1-768x511.jpg 768w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2022\/12\/DSC_4614-1-1536x1023.jpg 1536w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2022\/12\/DSC_4614-1-2048x1364.jpg 2048w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2022\/12\/DSC_4614-1-18x12.jpg 18w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e5a8d87\" data-id=\"e5a8d87\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6958444 elementor-widget elementor-widget-text-editor\" data-id=\"6958444\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Marzo 2023<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-77bb4df elementor-widget elementor-widget-heading\" data-id=\"77bb4df\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Micron milled blanking moulds<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9f1af30 elementor-widget elementor-widget-text-editor\" data-id=\"9f1af30\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>L&#8217; evento ha riunito una serie di fornitori di primo piano del Made in Italy manifatturiero per presentare e discutere un progetto portato a termine grazie al ricorso a tecnologie al&#8217;avanguardia e competenze all&#8217;avanguardia.<\/p><p style=\"text-align: right;\"><a href=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2023\/03\/marzo_2023.pdf\" target=\"_blank\" rel=\"noopener\">Vai all&#8217;articolo&#8230;<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8d7af78 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8d7af78\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-de30eab\" data-id=\"de30eab\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0d5a531 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"0d5a531\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f2bbe17 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f2bbe17\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-63c8941\" data-id=\"63c8941\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cc19dab elementor-widget elementor-widget-image\" data-id=\"cc19dab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1705\" src=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2022\/06\/DSC_3922-1-scaled.jpg\" class=\"attachment-full size-full wp-image-1196\" alt=\"\" srcset=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2022\/06\/DSC_3922-1-scaled.jpg 2560w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2022\/06\/DSC_3922-1-300x200.jpg 300w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2022\/06\/DSC_3922-1-1024x682.jpg 1024w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2022\/06\/DSC_3922-1-768x511.jpg 768w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2022\/06\/DSC_3922-1-1536x1023.jpg 1536w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2022\/06\/DSC_3922-1-2048x1364.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e895d48\" data-id=\"e895d48\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-05075e4 elementor-widget elementor-widget-text-editor\" data-id=\"05075e4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Febbraio 2023<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-451a195 elementor-widget elementor-widget-heading\" data-id=\"451a195\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Complex component in one shot<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4254c00 elementor-widget elementor-widget-text-editor\" data-id=\"4254c00\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Dal co-design del pezzo all&#8217;implementazione virtuale e reale del ciclo di fresatura per ottimizzare il processo e ridurre i rischi all&#8217;osso.<\/p><p style=\"text-align: right;\"><a href=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2023\/03\/febbraio_2023.pdf\" target=\"_blank\" rel=\"noopener\">Vai all&#8217;articolo&#8230;<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-86ed32d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"86ed32d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8445d94\" data-id=\"8445d94\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-55eb9d1 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"55eb9d1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-01e0f24 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"01e0f24\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4fc1951\" data-id=\"4fc1951\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-35d0fef elementor-widget elementor-widget-image\" data-id=\"35d0fef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1705\" src=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2022\/06\/DSC_3939-1-scaled.jpg\" class=\"attachment-full size-full wp-image-1201\" alt=\"\" srcset=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2022\/06\/DSC_3939-1-scaled.jpg 2560w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2022\/06\/DSC_3939-1-300x200.jpg 300w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2022\/06\/DSC_3939-1-1024x682.jpg 1024w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2022\/06\/DSC_3939-1-768x511.jpg 768w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2022\/06\/DSC_3939-1-1536x1023.jpg 1536w, https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2022\/06\/DSC_3939-1-2048x1364.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-a926cba\" data-id=\"a926cba\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4963c1a elementor-widget elementor-widget-text-editor\" data-id=\"4963c1a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ottobre 2022<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a6e9ea8 elementor-widget elementor-widget-heading\" data-id=\"a6e9ea8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Is it possible to machine a complex piece in one shot?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7370793 elementor-widget elementor-widget-text-editor\" data-id=\"7370793\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>A recent workshop organized by PoliMill gave some new information about how to machine complex components without hesitations.<\/p><p style=\"text-align: right;\"><a href=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2023\/03\/ottobre_2022.pdf\" target=\"_blank\" rel=\"noopener\">Vai all&#8217;articolo&#8230;<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0ace374 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0ace374\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-024a774\" data-id=\"024a774\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6c081b07 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6c081b07\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-232af1d2\" data-id=\"232af1d2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fab4509 elementor-widget elementor-widget-spacer\" data-id=\"fab4509\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6ba84672 elementor-widget elementor-widget-heading\" data-id=\"6ba84672\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Our Location<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-70acd4b4 elementor-section-full_width elementor-section-height-min-height elementor-section-height-default elementor-section-items-middle\" data-id=\"70acd4b4\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-20ce0809\" data-id=\"20ce0809\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-24243853\" data-id=\"24243853\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6f2c8fef elementor-widget elementor-widget-text-editor\" data-id=\"6f2c8fef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Politecnico di Milano <br \/>PoliMill Laboratory <br \/>Building B23<br \/>Via G. La Masa 1,<br \/>20156 Milano <br \/>Italy<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2c69dc41 e-grid-align-left elementor-shape-rounded elementor-grid-0 elementor-invisible elementor-widget elementor-widget-social-icons\" data-id=\"2c69dc41\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-linkedin elementor-animation-grow elementor-repeater-item-082644e\" href=\"https:\/\/www.linkedin.com\/company\/polimill\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Linkedin<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-linkedin\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-animation-grow elementor-repeater-item-3a1e282\" href=\"https:\/\/www.instagram.com\/polimill.polimi\/?igshid=ZWIzMWE5ZmU3Zg%3D%3D\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-instagram\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-e28baea\" data-id=\"e28baea\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4922a72a elementor-widget__width-auto elementor-widget elementor-widget-google_maps\" data-id=\"4922a72a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"google_maps.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-custom-embed\">\n\t\t\t<iframe loading=\"lazy\"\n\t\t\t\t\tsrc=\"https:\/\/maps.google.com\/maps?q=Via%20la%20Masa%201%20milano&#038;t=m&#038;z=12&#038;output=embed&#038;iwloc=near\"\n\t\t\t\t\ttitle=\"Via la Masa 1 milano\"\n\t\t\t\t\taria-label=\"Via la Masa 1 milano\"\n\t\t\t><\/iframe>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-c43da94\" data-id=\"c43da94\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Parlando di noi&#8230; Giugno 2026 Sgrossatura aggressiva Come spingere sull\u2019impostazione del ciclo di lavoro e sui parametri di taglio per aumentare la competitivit\u00e0 in termini di tempo mantenendo intatta la qualit\u00e0 richiesta. Vai all&#8217;articolo&#8230; Gennaio 2026 Come l&#8217;intelligenza artificiale aiuta le aziende manifatturiere Con questo articolo proseguiamo il monitoraggio del mercato dei software basati sull\u2019intelligenza [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"inline_featured_image":false,"ocean_front_end_style_editor":"no","ocean_post_layout":"full-screen","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"on","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"on","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","footnotes":""},"class_list":["post-2812","page","type-page","status-publish","hentry","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Parlando di noi... - PoliMill<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.polimill.polimi.it\/en\/parlando-di-noi\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Parlando di noi... - PoliMill\" \/>\n<meta property=\"og:description\" content=\"Parlando di noi&#8230; Giugno 2026 Sgrossatura aggressiva Come spingere sull\u2019impostazione del ciclo di lavoro e sui parametri di taglio per aumentare la competitivit\u00e0 in termini di tempo mantenendo intatta la qualit\u00e0 richiesta. Vai all&#8217;articolo&#8230; Gennaio 2026 Come l&#8217;intelligenza artificiale aiuta le aziende manifatturiere Con questo articolo proseguiamo il monitoraggio del mercato dei software basati sull\u2019intelligenza [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.polimill.polimi.it\/en\/parlando-di-noi\/\" \/>\n<meta property=\"og:site_name\" content=\"PoliMill\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-01T10:57:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2026\/06\/giugno_2026.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1085\" \/>\n\t<meta property=\"og:image:height\" content=\"949\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"15 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.polimill.polimi.it\\\/parlando-di-noi\\\/\",\"url\":\"https:\\\/\\\/www.polimill.polimi.it\\\/parlando-di-noi\\\/\",\"name\":\"Parlando di noi... - PoliMill\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.polimill.polimi.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.polimill.polimi.it\\\/parlando-di-noi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.polimill.polimi.it\\\/parlando-di-noi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.polimill.polimi.it\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/giugno_2026-1024x896.jpeg\",\"datePublished\":\"2023-03-02T08:52:21+00:00\",\"dateModified\":\"2026-09-01T10:57:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.polimill.polimi.it\\\/parlando-di-noi\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.polimill.polimi.it\\\/parlando-di-noi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.polimill.polimi.it\\\/parlando-di-noi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.polimill.polimi.it\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/giugno_2026-1024x896.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.polimill.polimi.it\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/giugno_2026-1024x896.jpeg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.polimill.polimi.it\\\/parlando-di-noi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.polimill.polimi.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Parlando di noi&#8230;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.polimill.polimi.it\\\/#website\",\"url\":\"https:\\\/\\\/www.polimill.polimi.it\\\/\",\"name\":\"PoliMill\",\"description\":\"Un laboratorio per la digitalizzazione dei processi di fresatura.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.polimill.polimi.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.polimill.polimi.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.polimill.polimi.it\\\/#organization\",\"name\":\"PoliMill\",\"url\":\"https:\\\/\\\/www.polimill.polimi.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.polimill.polimi.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.polimill.polimi.it\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/LOGO-BLACK-NO-VECTORS.png\",\"contentUrl\":\"https:\\\/\\\/www.polimill.polimi.it\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/LOGO-BLACK-NO-VECTORS.png\",\"width\":3054,\"height\":1232,\"caption\":\"PoliMill\"},\"image\":{\"@id\":\"https:\\\/\\\/www.polimill.polimi.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Parlando di noi... - PoliMill","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.polimill.polimi.it\/en\/parlando-di-noi\/","og_locale":"en_GB","og_type":"article","og_title":"Parlando di noi... - PoliMill","og_description":"Parlando di noi&#8230; Giugno 2026 Sgrossatura aggressiva Come spingere sull\u2019impostazione del ciclo di lavoro e sui parametri di taglio per aumentare la competitivit\u00e0 in termini di tempo mantenendo intatta la qualit\u00e0 richiesta. Vai all&#8217;articolo&#8230; Gennaio 2026 Come l&#8217;intelligenza artificiale aiuta le aziende manifatturiere Con questo articolo proseguiamo il monitoraggio del mercato dei software basati sull\u2019intelligenza [&hellip;]","og_url":"https:\/\/www.polimill.polimi.it\/en\/parlando-di-noi\/","og_site_name":"PoliMill","article_modified_time":"2026-09-01T10:57:19+00:00","og_image":[{"width":1085,"height":949,"url":"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2026\/06\/giugno_2026.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"15 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.polimill.polimi.it\/parlando-di-noi\/","url":"https:\/\/www.polimill.polimi.it\/parlando-di-noi\/","name":"Parlando di noi... - PoliMill","isPartOf":{"@id":"https:\/\/www.polimill.polimi.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.polimill.polimi.it\/parlando-di-noi\/#primaryimage"},"image":{"@id":"https:\/\/www.polimill.polimi.it\/parlando-di-noi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2026\/06\/giugno_2026-1024x896.jpeg","datePublished":"2023-03-02T08:52:21+00:00","dateModified":"2026-09-01T10:57:19+00:00","breadcrumb":{"@id":"https:\/\/www.polimill.polimi.it\/parlando-di-noi\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.polimill.polimi.it\/parlando-di-noi\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.polimill.polimi.it\/parlando-di-noi\/#primaryimage","url":"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2026\/06\/giugno_2026-1024x896.jpeg","contentUrl":"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2026\/06\/giugno_2026-1024x896.jpeg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.polimill.polimi.it\/parlando-di-noi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.polimill.polimi.it\/"},{"@type":"ListItem","position":2,"name":"Parlando di noi&#8230;"}]},{"@type":"WebSite","@id":"https:\/\/www.polimill.polimi.it\/#website","url":"https:\/\/www.polimill.polimi.it\/","name":"PoliMill","description":"A laboratory for the digitalization of chip removal processes","publisher":{"@id":"https:\/\/www.polimill.polimi.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.polimill.polimi.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.polimill.polimi.it\/#organization","name":"PoliMill","url":"https:\/\/www.polimill.polimi.it\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.polimill.polimi.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2022\/05\/LOGO-BLACK-NO-VECTORS.png","contentUrl":"https:\/\/www.polimill.polimi.it\/wp-content\/uploads\/2022\/05\/LOGO-BLACK-NO-VECTORS.png","width":3054,"height":1232,"caption":"PoliMill"},"image":{"@id":"https:\/\/www.polimill.polimi.it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.polimill.polimi.it\/en\/wp-json\/wp\/v2\/pages\/2812","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.polimill.polimi.it\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.polimill.polimi.it\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.polimill.polimi.it\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.polimill.polimi.it\/en\/wp-json\/wp\/v2\/comments?post=2812"}],"version-history":[{"count":251,"href":"https:\/\/www.polimill.polimi.it\/en\/wp-json\/wp\/v2\/pages\/2812\/revisions"}],"predecessor-version":[{"id":8845,"href":"https:\/\/www.polimill.polimi.it\/en\/wp-json\/wp\/v2\/pages\/2812\/revisions\/8845"}],"wp:attachment":[{"href":"https:\/\/www.polimill.polimi.it\/en\/wp-json\/wp\/v2\/media?parent=2812"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}